{"id":1765,"count":3,"description":"","link":"https:\/\/www.fahimai.com\/nl\/category\/ai\/automation\/linkedin\/linkedhelper","name":"LinkedHelper","slug":"linkedhelper","taxonomy":"category","parent":991,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/categories\/1765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/categories\/991"}],"wp:post_type":[{"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/posts?categories=1765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}