{"id":1668,"count":2,"description":"","link":"https:\/\/www.fahimai.com\/nl\/category\/software\/affiliate\/partner-io","name":"Partner IO","slug":"partner-io","taxonomy":"category","parent":681,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/categories\/1668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/categories\/681"}],"wp:post_type":[{"href":"https:\/\/www.fahimai.com\/nl\/wp-json\/wp\/v2\/posts?categories=1668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}